
{"id":18208,"date":"2026-05-12T15:20:41","date_gmt":"2026-05-12T13:20:41","guid":{"rendered":"https:\/\/ginn-hotels.com\/?page_id=18208"},"modified":"2026-05-13T11:23:30","modified_gmt":"2026-05-13T09:23:30","slug":"white-summer-dinner","status":"publish","type":"page","link":"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/","title":{"rendered":"White Summer Dinner"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"18208\" class=\"elementor elementor-18208\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12591b2c elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"12591b2c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:18451,&quot;url&quot;:&quot;https:\\\/\\\/ginn-hotels.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/he_whitediner_outdoor1.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e175874\" data-id=\"3e175874\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8bda47 elementor-widget elementor-widget-spacer\" data-id=\"a8bda47\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d802b24 animated-slow elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d802b24\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58d85ff animated-slow\" data-id=\"58d85ff\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ae28b1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1ae28b1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-sun\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe5216 elementor-widget elementor-widget-heading\" data-id=\"4fe5216\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">White Summer Dinner<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3341b elementor-widget elementor-widget-text-editor\" data-id=\"df3341b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" data-start=\"100\" data-end=\"209\">Erlebe ein unvergessliches White Summer Dinner \u00fcber den D\u00e4chern Hamburgs mit spektakul\u00e4rem Blick auf die Elbe<\/p><p style=\"text-align: center;\" data-start=\"211\" data-end=\"545\">Tauche ein in eine stilvolle Sommernacht ganz in Wei\u00df und genie\u00dfe ein exklusives Dinner-Erlebnis im GINN Hotel Hamburg Elbspeicher. <strong>Am 11. Juli 2026 ab 17 Uhr erwartet Dich auf der 8. Etage im GINN Restaurant<\/strong> und auf der Terrasse eine einzigartige Kombination aus kulinarischem Genuss, atemberaubender Aussicht und sommerlicher Atmosph\u00e4re.<br \/><br \/>Die Kombination aus Restaurant und Terrasse in der 8. Etage bietet Dir eine der sch\u00f6nsten Aussichten Hamburgs. Genie\u00dfe den Blick auf den Hafen und die Elbe w\u00e4hrend die Sonne langsam untergeht und die Stadt in warmes Licht taucht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7cca71 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7cca71\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#Buchung\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt reservieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a50980e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a50980e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3ef7f4\" data-id=\"d3ef7f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aad1a7b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"aad1a7b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg\" alt=\"IMG_1591\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-1024x683.jpg\" alt=\"he_whitedinner_drinks\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitediner_outdoor1-1024x683.jpg\" alt=\"he_whitediner_outdoor1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-1024x687.jpg\" alt=\"he_whitedinner_dresscode\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1585-1024x683.jpg\" alt=\"IMG_1585\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_outdoor2-1024x683.jpg\" alt=\"he_whitedinner_outdoor2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aedd029 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3aedd029\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-100d0c7e\" data-id=\"100d0c7e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b2c7471 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6b2c7471\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tshirt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f7c2200 elementor-widget elementor-widget-heading\" data-id=\"2f7c2200\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">White Dinner Event in Hamburg<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ea9e134 elementor-widget elementor-widget-text-editor\" data-id=\"4ea9e134\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Das White Summer Dinner ist mehr als nur ein Abendessen, es ist ein Erlebnis. Ganz im Zeichen des Dresscodes Wei\u00df erschaffst Du gemeinsam mit anderen G\u00e4sten eine elegante, harmonische Kulisse, die perfekt zur maritimen Umgebung und dem Sonnenuntergang \u00fcber der Elbe passt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32083927\" data-id=\"32083927\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ae7d73f elementor-widget elementor-widget-image\" data-id=\"3ae7d73f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"604\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-1024x687.jpg\" class=\"attachment-large size-large wp-image-18453\" alt=\"\" srcset=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-1024x687.jpg 1024w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-300x201.jpg 300w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-768x515.jpg 768w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-1536x1031.jpg 1536w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode-18x12.jpg 18w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_dresscode.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00ca5dd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"00ca5dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d8f1da\" data-id=\"1d8f1da\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43ee0cb0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"43ee0cb0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-utensils\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72b1de84 elementor-widget elementor-widget-heading\" data-id=\"72b1de84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Kulinarische Buffet Highlights<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34b64d2e elementor-widget elementor-widget-text-editor\" data-id=\"34b64d2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\" data-start=\"881\" data-end=\"1095\">Freue Dich auf ein hochwertiges Buffet f\u00fcr 45 Euro pro Person, das mit sommerlichen Spezialit\u00e4ten und abwechslungsreichen Gerichten \u00fcberzeugt. Perfekt abgestimmt auf einen genussvollen Abend in stilvollem Ambiente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba2d31a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ba2d31a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitesummerdinner_buffet.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Buffet entdecken<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b015924 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5b015924\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d6e025f\" data-id=\"1d6e025f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b742816 elementor-widget elementor-widget-image\" data-id=\"6b742816\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-1024x683.jpg\" class=\"attachment-large size-large wp-image-18454\" alt=\"\" srcset=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-1024x683.jpg 1024w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-300x200.jpg 300w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-768x512.jpg 768w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-1536x1024.jpg 1536w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks-18x12.jpg 18w, https:\/\/ginn-hotels.com\/wp-content\/uploads\/2026\/05\/he_whitedinner_drinks.jpg 2048w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5a45f919\" data-id=\"5a45f919\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eba09d6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"eba09d6\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cocktail\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec2c1d elementor-widget elementor-widget-heading\" data-id=\"1ec2c1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DRINKS & MEHR<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d3c7da elementor-widget elementor-widget-text-editor\" data-id=\"3d3c7da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Getr\u00e4nke sind exklusive und werden vor Ort bezahlt. Als besonderes Highlight erh\u00e4ltst Du beim Kauf einer Weinflasche kostenfrei Wasser dazu \u2013 ideal f\u00fcr einen entspannten Sommerabend mit Freunden oder Kollegen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a1901f animated-slow elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2a1901f\" data-element_type=\"section\" id=\"Buchung\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d5a784 animated-slow\" data-id=\"3d5a784\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12338a4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"12338a4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d33579b elementor-widget elementor-widget-heading\" data-id=\"d33579b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Book now<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b98efb3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b98efb3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400; text-align: center;\">Die Teilnahme erfolgt nach vorheriger Anmeldung. Die Zahlung f\u00fcr das Buffet erfolgt bequem vorab \u00fcber einen Zahlungslink, den wir Dir bei E-Mail zusenden. Deine Getr\u00e4nke begleichst Du direkt vor Ort.<br \/><br \/>Sichere Dir jetzt Deinen Platz f\u00fcr das White Summer Dinner und erlebe einen stilvollen Sommerabend \u00fcber der Elbe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2938248 elementor-widget elementor-widget-html\" data-id=\"2938248\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"teburio-Dhwtjhpd2irdBqXoQ\"><\/div>\n<script>(function( d, s, f, js, fjs) {\n  (js = d.createElement(s)), (fjs = d.getElementsByTagName(s)[0]);\n  js.src = f; js.async = 1;\n  fjs.parentNode.insertBefore(js, fjs);\n})( document, \"script\", \"https:\/\/static.teburio.de\/w2.js?e=Dhwtjhpd2irdBqXoQ\");\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fea273e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2fea273e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-354c6810\" data-id=\"354c6810\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-573fcacd elementor-widget elementor-widget-google_maps\" data-id=\"573fcacd\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=GINN%20Hotel%20Hamburg%20Elbspeicher%2C%20Gro%C3%9Fe%20Elbstra%C3%9Fe%2039%2C%2022767%20Hamburg&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"GINN Hotel Hamburg Elbspeicher, Gro\u00dfe Elbstra\u00dfe 39, 22767 Hamburg\"\n\t\t\t\t\taria-label=\"GINN Hotel Hamburg Elbspeicher, Gro\u00dfe Elbstra\u00dfe 39, 22767 Hamburg\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32b3e20f elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"32b3e20f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54b904ae\" data-id=\"54b904ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ac6127 hfe-nav-menu__breakpoint-none hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"55ac6127\" data-element_type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;220&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__none\" data-layout=\"horizontal\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-55ac6127\" class=\"hfe-nav-menu\"><li id=\"menu-item-375\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/jobs\/\" class = \"hfe-menu-item\">Jobs<\/a><\/li>\n<li id=\"menu-item-377\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/kontakt\/\" class = \"hfe-menu-item\">Contact<\/a><\/li>\n<li id=\"menu-item-374\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/impressum\/\" class = \"hfe-menu-item\">Imprint<\/a><\/li>\n<li id=\"menu-item-373\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/agb\/\" class = \"hfe-menu-item\">GTC<\/a><\/li>\n<li id=\"menu-item-376\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/datenschutz\/\" class = \"hfe-menu-item\">Data privacy<\/a><\/li>\n<li id=\"menu-item-15225\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/barrierfreiheitserklaerung\/\" class = \"hfe-menu-item\">Barrierefreiheit<\/a><\/li>\n<li id=\"menu-item-9557\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ginn-hotels.com\/en\/cookie-richtlinie-eu\/\" class = \"hfe-menu-item\">Cookie Directive (EU)<\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45be0b68\" data-id=\"45be0b68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-686a44d6 elementor-widget elementor-widget-copyright\" data-id=\"686a44d6\" data-element_type=\"widget\" data-settings=\"{&quot;align&quot;:&quot;right&quot;}\" data-widget_type=\"copyright.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hfe-copyright-wrapper\">\n\t\t\t\t\t\t\t<span>Copyright \u00a9 2026 GINN Hotels \/\/ <a href=\"http:\/\/www.hotelnetsolutions.de\">powered by HotelNetSolutions<\/a><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"White Summer Dinner Erlebe ein unvergessliches White Summer Dinner \u00fcber den D\u00e4chern Hamburgs mit spektakul\u00e4rem Blick auf die Elbe Tauche ein in eine stilvolle Sommernacht ganz in Wei\u00df und genie\u00dfe ein exklusives Dinner-Erlebnis im GINN Hotel Hamburg Elbspeicher. Am 11. Juli 2026 ab 17 Uhr erwartet Dich auf der 8. Etage im GINN Restaurant und&#8230; <a class=\"view-article\" href=\"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/\">View Article<\/a>","protected":false},"author":5,"featured_media":0,"parent":4694,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18208","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>White Summer Dinner | GINN Hotels<\/title>\n<meta name=\"description\" content=\"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White Summer Dinner | GINN Hotels\" \/>\n<meta property=\"og:description\" content=\"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/\" \/>\n<meta property=\"og:site_name\" content=\"GINN Hotels\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GINN.Hotels\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T09:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/\",\"url\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/\",\"name\":\"White Summer Dinner | GINN Hotels\",\"isPartOf\":{\"@id\":\"https:\/\/ginn-hotels.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg\",\"datePublished\":\"2026-05-12T13:20:41+00:00\",\"dateModified\":\"2026-05-13T09:23:30+00:00\",\"description\":\"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.\",\"breadcrumb\":{\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage\",\"url\":\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg\",\"contentUrl\":\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"HAMBURG ELBSPEICHER\",\"item\":\"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"White Summer Dinner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ginn-hotels.com\/#website\",\"url\":\"https:\/\/ginn-hotels.com\/\",\"name\":\"GINN Hotels\",\"description\":\"GINN Hotels | GINN City &amp; Lounge | GINN Apartments | GINN Restaurant | GINN Bar\",\"publisher\":{\"@id\":\"https:\/\/ginn-hotels.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ginn-hotels.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ginn-hotels.com\/#organization\",\"name\":\"GINN Hotels\",\"url\":\"https:\/\/ginn-hotels.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/ginn-hotels.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2020\/09\/ginn-hotels-main-logo-klein-2.jpg\",\"contentUrl\":\"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2020\/09\/ginn-hotels-main-logo-klein-2.jpg\",\"width\":280,\"height\":400,\"caption\":\"GINN Hotels\"},\"image\":{\"@id\":\"https:\/\/ginn-hotels.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GINN.Hotels\",\"https:\/\/www.instagram.com\/ginn.hotels\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"White Summer Dinner | GINN Hotels","description":"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/","og_locale":"en_GB","og_type":"article","og_title":"White Summer Dinner | GINN Hotels","og_description":"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.","og_url":"https:\/\/ginn-hotels.com\/en\/hamburgelbspeicher\/white-summer-dinner\/","og_site_name":"GINN Hotels","article_publisher":"https:\/\/www.facebook.com\/GINN.Hotels","article_modified_time":"2026-05-13T09:23:30+00:00","og_image":[{"url":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/","url":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/","name":"White Summer Dinner | GINN Hotels","isPartOf":{"@id":"https:\/\/ginn-hotels.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage"},"image":{"@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage"},"thumbnailUrl":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg","datePublished":"2026-05-12T13:20:41+00:00","dateModified":"2026-05-13T09:23:30+00:00","description":"White Summer Dinner \u00fcber der Elbe \u2013 stilvoll genie\u00dfen, ganz in Wei\u00df, mit spektakul\u00e4rem Ausblick.","breadcrumb":{"@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#primaryimage","url":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg","contentUrl":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/IMG_1591-1-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/white-summer-dinner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"HAMBURG ELBSPEICHER","item":"https:\/\/ginn-hotels.com\/hamburgelbspeicher\/"},{"@type":"ListItem","position":2,"name":"White Summer Dinner"}]},{"@type":"WebSite","@id":"https:\/\/ginn-hotels.com\/#website","url":"https:\/\/ginn-hotels.com\/","name":"GINN Hotels","description":"GINN Hotels | GINN City &amp; Lounge | GINN Apartments | GINN Restaurant | GINN Bar","publisher":{"@id":"https:\/\/ginn-hotels.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ginn-hotels.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ginn-hotels.com\/#organization","name":"GINN Hotels","url":"https:\/\/ginn-hotels.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ginn-hotels.com\/#\/schema\/logo\/image\/","url":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2020\/09\/ginn-hotels-main-logo-klein-2.jpg","contentUrl":"https:\/\/ginn-hotels.com\/wp-content\/uploads\/2020\/09\/ginn-hotels-main-logo-klein-2.jpg","width":280,"height":400,"caption":"GINN Hotels"},"image":{"@id":"https:\/\/ginn-hotels.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GINN.Hotels","https:\/\/www.instagram.com\/ginn.hotels"]}]}},"_links":{"self":[{"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/pages\/18208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/comments?post=18208"}],"version-history":[{"count":22,"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/pages\/18208\/revisions"}],"predecessor-version":[{"id":18488,"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/pages\/18208\/revisions\/18488"}],"up":[{"embeddable":true,"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/pages\/4694"}],"wp:attachment":[{"href":"https:\/\/ginn-hotels.com\/en\/wp-json\/wp\/v2\/media?parent=18208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}